{"id":772,"date":"2025-04-15T17:00:00","date_gmt":"2025-04-15T17:00:00","guid":{"rendered":"http:\/\/67fd9ee9d917f0098178175f"},"modified":"2025-04-15T17:00:00","modified_gmt":"2025-04-15T17:00:00","slug":"gemini-y-whisk-integran-veo-2-ahora-puedes-generar-videos-con-ia-a-partir-de-texto-e-imagenes","status":"publish","type":"post","link":"https:\/\/blog.tecnoartesanos.com\/index.php\/2025\/04\/15\/gemini-y-whisk-integran-veo-2-ahora-puedes-generar-videos-con-ia-a-partir-de-texto-e-imagenes\/","title":{"rendered":"Gemini y Whisk integran Veo 2: ahora puedes generar videos con IA a partir de texto e im\u00e1genes"},"content":{"rendered":"<div class=\"media_block\"><img decoding=\"async\" src=\"https:\/\/media.es.wired.com\/photos\/67fd9fea7f29b11b24257c08\/master\/pass\/Gemini_%20icy%20cavern%20(1).gif\" class=\"media_thumbnail\"><\/div>\n<p>A partir de hoy, los usuarios de <strong>Gemini Advanced<\/strong> y los suscriptores de <strong>Google One AI Premium<\/strong> podr\u00e1n generar videos utilizando <strong>Veo 2<\/strong>, el \u00faltimo modelo de generaci\u00f3n de videos de Google. Esta tecnolog\u00eda permite transformar <strong>descripciones de texto en videos din\u00e1micos de 8 segundos en 720p<\/strong>, as\u00ed como <strong>animar im\u00e1genes creadas en Whisk<\/strong>, el laboratorio experimental de IA <a href=\"https:\/\/es.wired.com\/articulos\/google-lanza-agent2agent-un-protocolo-para-que-los-agentes-de-ia-se-comuniquen-entre-si#intcid=_wired-es-right-rail_5227f643-7c3c-482b-831c-2dd85b0c3e67_popular4-2\">generativa de Google.<\/a><\/p>\n<hr>\n<div class=\"ContentCardEmbedWrapper-kULtsE iGAJsG content-card-embed content-card-embed--stacked\" data-testid=\"ContentCardEmbedWrapper\" readability=\"22.531835205993\">\n<div class=\"ContentCardEmbedImage-iwqgVw jlIubp content-card-embed__image\" data-testid=\"ContentCardEmbedImage\"><span class=\"SpanWrapper-umhxW jvZaPI responsive-asset\"><picture class=\"ResponsiveImagePicture-cWuUZO dUOtEa responsive-image\"><img decoding=\"async\" alt=\"Google executive Sissie Hsiao (center) with some of the team that works on the company\u2019s AI offerings (from left: Amar Subramanya, Jenny Blackburn, Suman Prasad, Trevor Strohman, and Jack Krawczyk) \" class=\"ResponsiveImageContainer-eybHBd fptoWY responsive-image__image\" src=\"https:\/\/media.es.wired.com\/photos\/67ddb212c2dc4f08809d887f\/master\/w_775%2Cc_limit\/GoogleAI_Thumbnail_SH.jpg\" srcset=\"https:\/\/media.es.wired.com\/photos\/67ddb212c2dc4f08809d887f\/master\/w_120,c_limit\/GoogleAI_Thumbnail_SH.jpg 120w, https:\/\/media.es.wired.com\/photos\/67ddb212c2dc4f08809d887f\/master\/w_240,c_limit\/GoogleAI_Thumbnail_SH.jpg 240w, https:\/\/media.es.wired.com\/photos\/67ddb212c2dc4f08809d887f\/master\/w_320,c_limit\/GoogleAI_Thumbnail_SH.jpg 320w, https:\/\/media.es.wired.com\/photos\/67ddb212c2dc4f08809d887f\/master\/w_640,c_limit\/GoogleAI_Thumbnail_SH.jpg 640w\" sizes=\"100vw\"><\/picture><\/span><\/div>\n<div class=\"ContentCardEmbedInfo-bDftKl bGnSrq\" readability=\"23.940074906367\">\n<div class=\"BaseWrap-sc-gjQpdd BaseText-ewhhUZ ContentCardEmbedHed-kJVPGC iUEiRd cekThb cewqFA content-card-embed__hed\" data-testid=\"ContentCardEmbedHed\"><a class=\"BaseWrap-sc-gjQpdd BaseText-ewhhUZ BaseLink-eNWuiM ContentCardEmbedHedLink-eXLwe iUEiRd cekThb gqhxzW eFUKSb content-card-embed__hed-link\" href=\"https:\/\/es.wired.com\/articulos\/la-frenetica-carrera-que-google-emprendio-para-alcanzar-a-openai-en-dos-anos\" data-testid=\"ContentCardEmbedHedLink\">La fren\u00e9tica carrera que Google emprendi\u00f3 para alcanzar a OpenAI en dos a\u00f1os<\/a><\/div>\n<p>La gigante de las b\u00fasquedas deber\u00eda haber sido la primera en llegar a la revoluci\u00f3n de los <em>chatbot<\/em>. No lo fue. As\u00ed que contraatac\u00f3 con madrugones, despidos y bajando algunas barreras.<\/p>\n<\/div>\n<\/div>\n<hr>\n<p><strong>Creaci\u00f3n de videos en Gemini con Veo 2<\/strong><\/p>\n<p>Veo 2 marca un avanceen la generaci\u00f3n de videos, ofreciendo resultados con <strong>realismo cinematogr\u00e1fico<\/strong>, movimientos fluidos y detalles visuales mejorados. El modelo interpreta mejor la f\u00edsica del mundo real y los movimientos humanos, lo que permite crear escenas m\u00e1s realistas y variadas en m\u00faltiples estilos, desde lo fant\u00e1stico hasta lo hiperrealista.<\/p>\n<p>Para usarlo, los suscriptores de <strong>Gemini Advanced<\/strong> solo deben:<\/p>\n<ol>\n<li>Seleccionar <strong>Veo 2<\/strong> en el men\u00fa desplegable de modelos.<\/li>\n<\/ol>\n<p>2. Describir con detalle la escena que desean generar (una historia corta, un concepto visual, etc.).<\/p>\n<p>3. Recibir el video en formato <strong>MP4 (16:9)<\/strong>, listo para compartir en redes como <strong>TikTok o YouTube Shorts<\/strong>.<\/p>\n<p>La funci\u00f3n, disponible desde hoy en la web y la app m\u00f3vil de Gemini (con despliegue progresivo en las pr\u00f3ximas semanas), tiene un <strong>l\u00edmite mensual de generaciones<\/strong>, aunque Google notificar\u00e1 a los usuarios cuando se acerquen a ese tope.<\/p>\n<p><strong>Whisk Animate: convierte im\u00e1genes en videos<\/strong><\/p>\n<p>Por su parte, <strong>Whisk<\/strong>, la herramienta experimental de Google Labs, estrena <strong>Whisk Animate<\/strong>, una funci\u00f3n exclusiva para suscriptores de <strong>Google One AI Premium<\/strong>. Los usuarios podr\u00e1n tomar cualquier imagen generada en Whisk (mediante texto o otra imagen) y animarla autom\u00e1ticamente en un clip de 8 segundos con Veo 2.<\/p>\n<p><strong>Seguridad y transparencia<\/strong><\/p>\n<p>Google asegura que ha implementado medidas para garantizar un uso responsable, incluyendo:<\/p>\n<p><strong>Evaluaciones exhaustivas<\/strong> (&#8220;red teaming&#8221;) para evitar contenido violatorio.<\/p>\n<p><strong>SynthID<\/strong>, una marca de agua digital incrustada en cada fotograma que identifica los videos como generados por IA.<\/p>\n<p>Aun as\u00ed, la compa\u00f1\u00eda reconoce que, como en cualquier IA generativa, pueden surgir resultados no deseados, por lo que invita a los usuarios a enviar <strong>feedback<\/strong> mediante los botones de &#8220;me gusta\/no me gusta&#8221;.<\/p>\n<p><strong>Disponibilidad<\/strong><\/p>\n<p><strong>Gemini Advanced<\/strong>: Acceso a generaci\u00f3n de videos con Veo 2 en <a href=\"https:\/\/gemini.google.com\/\" target=\"_blank\">gemini.google.com<\/a>.<\/p>\n<p><strong>Google One AI Premium<\/strong>: Whisk Animate en <a data-offer-url=\"https:\/\/labs.google\/whisk\" class=\"external-link\" data-event-click=\"{&quot;element&quot;:&quot;ExternalLink&quot;,&quot;outgoingURL&quot;:&quot;https:\/\/labs.google\/whisk&quot;}\" href=\"https:\/\/labs.google\/whisk\" rel=\"nofollow noopener\" target=\"_blank\">labs.google\/whisk<\/a>.<\/p>\n<p>Con estas novedades, Google acerca la creaci\u00f3n audiovisual a un p\u00fablico m\u00e1s amplio, eliminando la necesidad de equipos especializados o conocimientos t\u00e9cnicos. \u00bfEl l\u00edmite? La imaginaci\u00f3n del usuario.<\/p>\n<h2>Google prepara unos lentes de realidad virtual con Gemini<\/h2>\n<p><strong>Durante el evento TED 2025 en Vancouver, se vivi\u00f3 una aparici\u00f3n inesperada y espectacular: la presentaci\u00f3n en vivo de los prototipos de gafas inteligentes con la nueva plataforma Android XR.<\/strong> Shahram Izadi, l\u00edder del desarrollo de realidad mixta en Google sorprendi\u00f3 al p\u00fablico al subir al escenario usando un par. En lugar de limitarse a explicar las capacidades del proyecto, Izadi opt\u00f3 por mostrar el dispositivo en acci\u00f3n, destacando las posibilidades que ofrece la integraci\u00f3n con Gemini, el asistente de IA de Google.<\/p>\n<p>Actualmente, dos gigantes tecnol\u00f3gicas trabajan en el desarrollo de Android XR: Google y Samsung. Cada uno ha tomado caminos distintos en cuanto a dise\u00f1o y enfoque. Por ejemplo, en el evento Unpacked de enero, <strong>Samsung present\u00f3 la gama de <em>smatphones<\/em> <a href=\"https:\/\/es.wired.com\/articulos\/todo-lo-que-sabemos-sobre-el-proximo-galaxy-s25-edge\">Galaxy S25<\/a>, a la par de su visor de realidad virtual (RV), a\u00fan conocido como <a href=\"https:\/\/es.wired.com\/review\/probamos-el-poder-de-android-xr-y-las-gafas-inteligentes-de-google-con-ia\">Project Moohan<\/a>.<\/strong> Este dispositivo, que compite directamente con las <a href=\"https:\/\/es.wired.com\/articulos\/apple-vision-pro-vale-la-pena-comprar-estas-gafas-de-realidad-mixta\">Vision Pro de Apple<\/a>, tambi\u00e9n integra Android XR y est\u00e1 orientado a experiencias inmersivas de realidad virtual y multitarea.<\/p>\n<p><strong>Google, en cambio, ha apostado por unas gafas inteligentes mucho m\u00e1s discretas, similares en apariencia a unas gafas tradicionales, como las populares <a href=\"https:\/\/es.wired.com\/articulos\/ray-ban-y-meta-anuncian-una-nueva-edicion-limitada-de-gafas\">Ray-Ban Meta<\/a>.<\/strong> A pesar de su dise\u00f1o delgado, estos prototipos esconden un <em>hardware<\/em> avanzado en sus patillas, incluyendo c\u00e1maras frontales que permiten superponer informaci\u00f3n en tiempo real en los lentes. Durante la demostraci\u00f3n, se mostraron funciones como navegaci\u00f3n GPS giro a giro y reconocimiento contextual de objetos, todo proyectado directamente sobre el campo visual del usuario.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de hoy, los usuarios de Gemini Advanced y los suscriptores de Google One AI Premium podr\u00e1n generar videos utilizando Veo 2, el \u00faltimo modelo de generaci\u00f3n de videos de Google. Esta tecnolog\u00eda permite transformar descripciones de texto en videos din\u00e1micos de 8 segundos en 720p, as\u00ed como animar im\u00e1genes creadas en Whisk, el [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":773,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-772","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technology"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gemini y Whisk integran Veo 2: ahora puedes generar videos con IA a partir de texto e im\u00e1genes - TecnoArtesanos Tech Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.tecnoartesanos.com\/index.php\/2025\/04\/15\/gemini-y-whisk-integran-veo-2-ahora-puedes-generar-videos-con-ia-a-partir-de-texto-e-imagenes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gemini y Whisk integran Veo 2: ahora puedes generar videos con IA a partir de texto e im\u00e1genes - TecnoArtesanos Tech Blog\" \/>\n<meta property=\"og:description\" content=\"A partir de hoy, los usuarios de Gemini Advanced y los suscriptores de Google One AI Premium podr\u00e1n generar videos utilizando Veo 2, el \u00faltimo modelo de generaci\u00f3n de videos de Google. Esta tecnolog\u00eda permite transformar descripciones de texto en videos din\u00e1micos de 8 segundos en 720p, as\u00ed como animar im\u00e1genes creadas en Whisk, el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.tecnoartesanos.com\/index.php\/2025\/04\/15\/gemini-y-whisk-integran-veo-2-ahora-puedes-generar-videos-con-ia-a-partir-de-texto-e-imagenes\/\" \/>\n<meta property=\"og:site_name\" content=\"TecnoArtesanos Tech Blog\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-15T17:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.es.wired.com\/photos\/67fd9fea7f29b11b24257c08\/master\/pass\/Gemini_%20icy%20cavern%20(1).gif\" \/>\n<meta name=\"author\" content=\"Sergio Morales\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sergio Morales\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.tecnoartesanos.com\/index.php\/2025\/04\/15\/gemini-y-whisk-integran-veo-2-ahora-puedes-generar-videos-con-ia-a-partir-de-texto-e-imagenes\/\",\"url\":\"https:\/\/blog.tecnoartesanos.com\/index.php\/2025\/04\/15\/gemini-y-whisk-integran-veo-2-ahora-puedes-generar-videos-con-ia-a-partir-de-texto-e-imagenes\/\",\"name\":\"Gemini y Whisk integran Veo 2: ahora puedes generar videos con IA a partir de texto e im\u00e1genes - TecnoArtesanos Tech Blog\",\"isPartOf\":{\"@id\":\"https:\/\/blog.tecnoartesanos.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blog.tecnoartesanos.com\/index.php\/2025\/04\/15\/gemini-y-whisk-integran-veo-2-ahora-puedes-generar-videos-con-ia-a-partir-de-texto-e-imagenes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blog.tecnoartesanos.com\/index.php\/2025\/04\/15\/gemini-y-whisk-integran-veo-2-ahora-puedes-generar-videos-con-ia-a-partir-de-texto-e-imagenes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.tecnoartesanos.com\/wp-content\/uploads\/2025\/04\/gemini-y-whisk-integran-veo-2-ahora-puedes-generar-videos-con-ia-a-partir-de-texto-e-imagenes.jpg\",\"datePublished\":\"2025-04-15T17:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/blog.tecnoartesanos.com\/#\/schema\/person\/ec88bc1410fd158963717c4216f04807\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.tecnoartesanos.com\/index.php\/2025\/04\/15\/gemini-y-whisk-integran-veo-2-ahora-puedes-generar-videos-con-ia-a-partir-de-texto-e-imagenes\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.tecnoartesanos.com\/index.php\/2025\/04\/15\/gemini-y-whisk-integran-veo-2-ahora-puedes-generar-videos-con-ia-a-partir-de-texto-e-imagenes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/blog.tecnoartesanos.com\/index.php\/2025\/04\/15\/gemini-y-whisk-integran-veo-2-ahora-puedes-generar-videos-con-ia-a-partir-de-texto-e-imagenes\/#primaryimage\",\"url\":\"https:\/\/blog.tecnoartesanos.com\/wp-content\/uploads\/2025\/04\/gemini-y-whisk-integran-veo-2-ahora-puedes-generar-videos-con-ia-a-partir-de-texto-e-imagenes.jpg\",\"contentUrl\":\"https:\/\/blog.tecnoartesanos.com\/wp-content\/uploads\/2025\/04\/gemini-y-whisk-integran-veo-2-ahora-puedes-generar-videos-con-ia-a-partir-de-texto-e-imagenes.jpg\",\"width\":775,\"height\":517},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.tecnoartesanos.com\/index.php\/2025\/04\/15\/gemini-y-whisk-integran-veo-2-ahora-puedes-generar-videos-con-ia-a-partir-de-texto-e-imagenes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.tecnoartesanos.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gemini y Whisk integran Veo 2: ahora puedes generar videos con IA a partir de texto e im\u00e1genes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.tecnoartesanos.com\/#website\",\"url\":\"https:\/\/blog.tecnoartesanos.com\/\",\"name\":\"TecnoArtesanos Tech Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.tecnoartesanos.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blog.tecnoartesanos.com\/#\/schema\/person\/ec88bc1410fd158963717c4216f04807\",\"name\":\"Sergio Morales\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/blog.tecnoartesanos.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3d45178fc8fbbe32d39278bc504fa9093f947f406ff4f1ddcfa27505ab772184?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3d45178fc8fbbe32d39278bc504fa9093f947f406ff4f1ddcfa27505ab772184?s=96&d=mm&r=g\",\"caption\":\"Sergio Morales\"},\"sameAs\":[\"https:\/\/sergiomorales.space\"],\"url\":\"https:\/\/blog.tecnoartesanos.com\/index.php\/author\/sergiomorales\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gemini y Whisk integran Veo 2: ahora puedes generar videos con IA a partir de texto e im\u00e1genes - TecnoArtesanos Tech Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.tecnoartesanos.com\/index.php\/2025\/04\/15\/gemini-y-whisk-integran-veo-2-ahora-puedes-generar-videos-con-ia-a-partir-de-texto-e-imagenes\/","og_locale":"en_US","og_type":"article","og_title":"Gemini y Whisk integran Veo 2: ahora puedes generar videos con IA a partir de texto e im\u00e1genes - TecnoArtesanos Tech Blog","og_description":"A partir de hoy, los usuarios de Gemini Advanced y los suscriptores de Google One AI Premium podr\u00e1n generar videos utilizando Veo 2, el \u00faltimo modelo de generaci\u00f3n de videos de Google. Esta tecnolog\u00eda permite transformar descripciones de texto en videos din\u00e1micos de 8 segundos en 720p, as\u00ed como animar im\u00e1genes creadas en Whisk, el [&hellip;]","og_url":"https:\/\/blog.tecnoartesanos.com\/index.php\/2025\/04\/15\/gemini-y-whisk-integran-veo-2-ahora-puedes-generar-videos-con-ia-a-partir-de-texto-e-imagenes\/","og_site_name":"TecnoArtesanos Tech Blog","article_published_time":"2025-04-15T17:00:00+00:00","og_image":[{"url":"https:\/\/media.es.wired.com\/photos\/67fd9fea7f29b11b24257c08\/master\/pass\/Gemini_%20icy%20cavern%20(1).gif","type":"","width":"","height":""}],"author":"Sergio Morales","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Sergio Morales","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.tecnoartesanos.com\/index.php\/2025\/04\/15\/gemini-y-whisk-integran-veo-2-ahora-puedes-generar-videos-con-ia-a-partir-de-texto-e-imagenes\/","url":"https:\/\/blog.tecnoartesanos.com\/index.php\/2025\/04\/15\/gemini-y-whisk-integran-veo-2-ahora-puedes-generar-videos-con-ia-a-partir-de-texto-e-imagenes\/","name":"Gemini y Whisk integran Veo 2: ahora puedes generar videos con IA a partir de texto e im\u00e1genes - TecnoArtesanos Tech Blog","isPartOf":{"@id":"https:\/\/blog.tecnoartesanos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.tecnoartesanos.com\/index.php\/2025\/04\/15\/gemini-y-whisk-integran-veo-2-ahora-puedes-generar-videos-con-ia-a-partir-de-texto-e-imagenes\/#primaryimage"},"image":{"@id":"https:\/\/blog.tecnoartesanos.com\/index.php\/2025\/04\/15\/gemini-y-whisk-integran-veo-2-ahora-puedes-generar-videos-con-ia-a-partir-de-texto-e-imagenes\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.tecnoartesanos.com\/wp-content\/uploads\/2025\/04\/gemini-y-whisk-integran-veo-2-ahora-puedes-generar-videos-con-ia-a-partir-de-texto-e-imagenes.jpg","datePublished":"2025-04-15T17:00:00+00:00","author":{"@id":"https:\/\/blog.tecnoartesanos.com\/#\/schema\/person\/ec88bc1410fd158963717c4216f04807"},"breadcrumb":{"@id":"https:\/\/blog.tecnoartesanos.com\/index.php\/2025\/04\/15\/gemini-y-whisk-integran-veo-2-ahora-puedes-generar-videos-con-ia-a-partir-de-texto-e-imagenes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.tecnoartesanos.com\/index.php\/2025\/04\/15\/gemini-y-whisk-integran-veo-2-ahora-puedes-generar-videos-con-ia-a-partir-de-texto-e-imagenes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blog.tecnoartesanos.com\/index.php\/2025\/04\/15\/gemini-y-whisk-integran-veo-2-ahora-puedes-generar-videos-con-ia-a-partir-de-texto-e-imagenes\/#primaryimage","url":"https:\/\/blog.tecnoartesanos.com\/wp-content\/uploads\/2025\/04\/gemini-y-whisk-integran-veo-2-ahora-puedes-generar-videos-con-ia-a-partir-de-texto-e-imagenes.jpg","contentUrl":"https:\/\/blog.tecnoartesanos.com\/wp-content\/uploads\/2025\/04\/gemini-y-whisk-integran-veo-2-ahora-puedes-generar-videos-con-ia-a-partir-de-texto-e-imagenes.jpg","width":775,"height":517},{"@type":"BreadcrumbList","@id":"https:\/\/blog.tecnoartesanos.com\/index.php\/2025\/04\/15\/gemini-y-whisk-integran-veo-2-ahora-puedes-generar-videos-con-ia-a-partir-de-texto-e-imagenes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.tecnoartesanos.com\/"},{"@type":"ListItem","position":2,"name":"Gemini y Whisk integran Veo 2: ahora puedes generar videos con IA a partir de texto e im\u00e1genes"}]},{"@type":"WebSite","@id":"https:\/\/blog.tecnoartesanos.com\/#website","url":"https:\/\/blog.tecnoartesanos.com\/","name":"TecnoArtesanos Tech Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.tecnoartesanos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/blog.tecnoartesanos.com\/#\/schema\/person\/ec88bc1410fd158963717c4216f04807","name":"Sergio Morales","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blog.tecnoartesanos.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3d45178fc8fbbe32d39278bc504fa9093f947f406ff4f1ddcfa27505ab772184?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3d45178fc8fbbe32d39278bc504fa9093f947f406ff4f1ddcfa27505ab772184?s=96&d=mm&r=g","caption":"Sergio Morales"},"sameAs":["https:\/\/sergiomorales.space"],"url":"https:\/\/blog.tecnoartesanos.com\/index.php\/author\/sergiomorales\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/posts\/772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/comments?post=772"}],"version-history":[{"count":0,"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/posts\/772\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/media\/773"}],"wp:attachment":[{"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/media?parent=772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/categories?post=772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/tags?post=772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}