{"id":2440,"date":"2026-03-27T16:42:02","date_gmt":"2026-03-27T16:42:02","guid":{"rendered":"http:\/\/69c6a3695a209ca84ef7fdfb"},"modified":"2026-03-27T16:42:02","modified_gmt":"2026-03-27T16:42:02","slug":"una-jueza-pone-en-pausa-la-ofensiva-de-trump-contra-anthropic","status":"publish","type":"post","link":"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/27\/una-jueza-pone-en-pausa-la-ofensiva-de-trump-contra-anthropic\/","title":{"rendered":"Una jueza pone en pausa la ofensiva de Trump contra Anthropic"},"content":{"rendered":"<div class=\"media_block\"><img decoding=\"async\" src=\"https:\/\/media.es.wired.com\/photos\/69c6a3695a209ca84ef7fdf9\/master\/pass\/Apple-Supply-Chain-Risk-Business-2261514689.jpg\" class=\"media_thumbnail\"><\/div>\n<div><img decoding=\"async\" src=\"https:\/\/media.es.wired.com\/photos\/69c6a3695a209ca84ef7fdf9\/16:9\/w_1280,c_limit\/Apple-Supply-Chain-Risk-Business-2261514689.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p><strong>Anthropic ha obtenido una medida cautelar que impide al Departamento de Defensa de EE UU etiquetarla como riesgo para la cadena de suministro<\/strong>, lo que podr\u00eda despejar el camino para que los clientes reanuden su colaboraci\u00f3n con la empresa. La sentencia dictada el jueves por Rita Lin, jueza federal de distrito en San Francisco, supone un rev\u00e9s simb\u00f3lico para el Pent\u00e1gono y un importante impulso para la empresa de IA generativa en su intento de preservar su negocio y su reputaci\u00f3n.<\/p>\n<p>&#8220;Es probable que la designaci\u00f3n de Anthropic como &#8216;riesgo para la cadena de suministro&#8217; por parte de los demandados sea contraria a la ley y arbitraria y caprichosa&#8221;, escribi\u00f3 Lin al justificar la medida cautelar. &#8220;El Departamento de Guerra no ofrece ninguna base leg\u00edtima para inferir, a partir de la insistencia de Anthropic en las restricciones de uso, que podr\u00eda convertirse en un saboteador&#8221;.<\/p>\n<p>Anthropic y el Pent\u00e1gono no respondieron de inmediato a las solicitudes de comentarios sobre el fallo.<\/p>\n<h2>El recuento de los hechos<\/h2>\n<p>El Departamento de Defensa, que bajo Trump se llama a s\u00ed mismo el Departamento de Guerra, ha confiado en las herramientas de IA <a href=\"https:\/\/es.wired.com\/articulos\/la-eficiencia-de-claude-ia-de-anthropic-desata-panico-laboral-y-hunde-la-bolsa-india\">Claude de Anthropic<\/a> para redactar documentos sensibles y analizar datos clasificados en los \u00faltimos dos a\u00f1os. Pero este mes, comenz\u00f3 a retirar Claude despu\u00e9s de determinar que <a href=\"https:\/\/es.wired.com\/articulos\/el-departamento-de-justicia-dice-que-no-se-puede-confiar-en-anthropic-para-los-sistemas-de-combate\">Anthropic no era de fiar.<\/a> Los funcionarios del Pent\u00e1gono citaron numerosos casos en los que Anthropic supuestamente puso o intent\u00f3 poner restricciones de uso en su tecnolog\u00eda que la administraci\u00f3n Trump consider\u00f3 innecesarias.<\/p>\n<p>La administraci\u00f3n finalmente emiti\u00f3 varias directivas, incluida la designaci\u00f3n de la empresa como un riesgo para la cadena de suministro, que han tenido el efecto de detener lentamente el uso de Claude en todo el gobierno federal y da\u00f1ar las ventas y <a href=\"https:\/\/es.wired.com\/articulos\/a-diferencia-de-anthropic-openai-cede-al-pentagono-uso-legal-de-su-ia-para-fines-militares\">la reputaci\u00f3n p\u00fablica de Anthropic.<\/a> La empresa present\u00f3 dos demandas contra las sanciones por inconstitucionales. En una audiencia celebrada el martes, Lin afirm\u00f3 que el gobierno parec\u00eda haber perjudicado y castigado ilegalmente a Anthropic.<\/p>\n<p>La sentencia de Lin del jueves &#8220;restablece el statu quo&#8221; al 27 de febrero, antes de que se emitieran las directivas. &#8220;No impide a ning\u00fan acusado emprender ninguna acci\u00f3n legal que hubiera tenido a su disposici\u00f3n en esa fecha. Por ejemplo, esta orden no requiere que el Departamento de Guerra utilice los <a href=\"https:\/\/es.wired.com\/articulos\/anthropic-quiere-que-su-ia-controle-tu-computadora-y-de-paso-el-mercado\">productos o servicios de Anthropic<\/a> y no impide que el departamento realice la transici\u00f3n a otros proveedores de IA, siempre que esas acciones sean coherentes con las regulaciones, estatutos y disposiciones constitucionales aplicables&#8221;.<\/p>\n<h2>Qu\u00e9 dice la sentencia<\/h2>\n<p>El fallo sugiere que el Pent\u00e1gono y otras agencias federales a\u00fan tienen la libertad de cancelar acuerdos con Anthropic y pedir a los contratistas que integran Claude en sus propias herramientas que dejen de hacerlo, pero sin citar la designaci\u00f3n de riesgo en la cadena de suministro como base.<\/p>\n<p>El impacto inmediato no est\u00e1 claro porque la orden de Lin no entrar\u00e1 en vigor hasta dentro de una semana. Adem\u00e1s, un tribunal federal de apelaciones de Washington DC a\u00fan no se ha pronunciado sobre la segunda demanda interpuesta por Anthropic, que se centra en otra ley en virtud de la cual tambi\u00e9n se prohibi\u00f3 a la empresa <a href=\"https:\/\/es.wired.com\/articulos\/openai-hace-alianza-con-anduril-para-suministrar-ia-al-ejercito-de-ee-uu\">suministrar <em>software<\/em> al ej\u00e9rcito.<\/a><\/p>\n<p>Pero Anthropic podr\u00eda utilizar la sentencia de Lin para demostrar a algunos clientes preocupados por trabajar con un paria de la industria que la ley puede estar de su lado a largo plazo. <strong>Lin no ha fijado un calendario para dictar una sentencia definitiva.<\/strong><\/p>\n<p><em>Art\u00edculo originalmente publicado en<\/em> <a href=\"https:\/\/www.wired.com\/story\/anthropic-supply-chain-risk-designation-injunction\/\">WIRED.<\/a> <em>Adaptado por Alondra Flores.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anthropic ha obtenido una medida cautelar que impide al Departamento de Defensa de EE UU etiquetarla como riesgo para la cadena de suministro, lo que podr\u00eda despejar el camino para que los clientes reanuden su colaboraci\u00f3n con la empresa. La sentencia dictada el jueves por Rita Lin, jueza federal de distrito en San Francisco, supone [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2441,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2440","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technology"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Una jueza pone en pausa la ofensiva de Trump contra Anthropic - TecnoArtesanos Tech Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/27\/una-jueza-pone-en-pausa-la-ofensiva-de-trump-contra-anthropic\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una jueza pone en pausa la ofensiva de Trump contra Anthropic - TecnoArtesanos Tech Blog\" \/>\n<meta property=\"og:description\" content=\"Anthropic ha obtenido una medida cautelar que impide al Departamento de Defensa de EE UU etiquetarla como riesgo para la cadena de suministro, lo que podr\u00eda despejar el camino para que los clientes reanuden su colaboraci\u00f3n con la empresa. La sentencia dictada el jueves por Rita Lin, jueza federal de distrito en San Francisco, supone [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/27\/una-jueza-pone-en-pausa-la-ofensiva-de-trump-contra-anthropic\/\" \/>\n<meta property=\"og:site_name\" content=\"TecnoArtesanos Tech Blog\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-27T16:42:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.es.wired.com\/photos\/69c6a3695a209ca84ef7fdf9\/master\/pass\/Apple-Supply-Chain-Risk-Business-2261514689.jpg\" \/>\n<meta name=\"author\" content=\"Sergio Morales\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sergio Morales\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/27\/una-jueza-pone-en-pausa-la-ofensiva-de-trump-contra-anthropic\/\",\"url\":\"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/27\/una-jueza-pone-en-pausa-la-ofensiva-de-trump-contra-anthropic\/\",\"name\":\"Una jueza pone en pausa la ofensiva de Trump contra Anthropic - TecnoArtesanos Tech Blog\",\"isPartOf\":{\"@id\":\"https:\/\/blog.tecnoartesanos.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/27\/una-jueza-pone-en-pausa-la-ofensiva-de-trump-contra-anthropic\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/27\/una-jueza-pone-en-pausa-la-ofensiva-de-trump-contra-anthropic\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.tecnoartesanos.com\/wp-content\/uploads\/2026\/03\/una-jueza-pone-en-pausa-la-ofensiva-de-trump-contra-anthropic.jpg\",\"datePublished\":\"2026-03-27T16:42:02+00:00\",\"author\":{\"@id\":\"https:\/\/blog.tecnoartesanos.com\/#\/schema\/person\/ec88bc1410fd158963717c4216f04807\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/27\/una-jueza-pone-en-pausa-la-ofensiva-de-trump-contra-anthropic\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/27\/una-jueza-pone-en-pausa-la-ofensiva-de-trump-contra-anthropic\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/27\/una-jueza-pone-en-pausa-la-ofensiva-de-trump-contra-anthropic\/#primaryimage\",\"url\":\"https:\/\/blog.tecnoartesanos.com\/wp-content\/uploads\/2026\/03\/una-jueza-pone-en-pausa-la-ofensiva-de-trump-contra-anthropic.jpg\",\"contentUrl\":\"https:\/\/blog.tecnoartesanos.com\/wp-content\/uploads\/2026\/03\/una-jueza-pone-en-pausa-la-ofensiva-de-trump-contra-anthropic.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/27\/una-jueza-pone-en-pausa-la-ofensiva-de-trump-contra-anthropic\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.tecnoartesanos.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una jueza pone en pausa la ofensiva de Trump contra Anthropic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.tecnoartesanos.com\/#website\",\"url\":\"https:\/\/blog.tecnoartesanos.com\/\",\"name\":\"TecnoArtesanos Tech Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.tecnoartesanos.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blog.tecnoartesanos.com\/#\/schema\/person\/ec88bc1410fd158963717c4216f04807\",\"name\":\"Sergio Morales\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/blog.tecnoartesanos.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3d45178fc8fbbe32d39278bc504fa9093f947f406ff4f1ddcfa27505ab772184?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3d45178fc8fbbe32d39278bc504fa9093f947f406ff4f1ddcfa27505ab772184?s=96&d=mm&r=g\",\"caption\":\"Sergio Morales\"},\"sameAs\":[\"https:\/\/sergiomorales.space\"],\"url\":\"https:\/\/blog.tecnoartesanos.com\/index.php\/author\/sergiomorales\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una jueza pone en pausa la ofensiva de Trump contra Anthropic - TecnoArtesanos Tech Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/27\/una-jueza-pone-en-pausa-la-ofensiva-de-trump-contra-anthropic\/","og_locale":"en_US","og_type":"article","og_title":"Una jueza pone en pausa la ofensiva de Trump contra Anthropic - TecnoArtesanos Tech Blog","og_description":"Anthropic ha obtenido una medida cautelar que impide al Departamento de Defensa de EE UU etiquetarla como riesgo para la cadena de suministro, lo que podr\u00eda despejar el camino para que los clientes reanuden su colaboraci\u00f3n con la empresa. La sentencia dictada el jueves por Rita Lin, jueza federal de distrito en San Francisco, supone [&hellip;]","og_url":"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/27\/una-jueza-pone-en-pausa-la-ofensiva-de-trump-contra-anthropic\/","og_site_name":"TecnoArtesanos Tech Blog","article_published_time":"2026-03-27T16:42:02+00:00","og_image":[{"url":"https:\/\/media.es.wired.com\/photos\/69c6a3695a209ca84ef7fdf9\/master\/pass\/Apple-Supply-Chain-Risk-Business-2261514689.jpg","type":"","width":"","height":""}],"author":"Sergio Morales","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Sergio Morales","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/27\/una-jueza-pone-en-pausa-la-ofensiva-de-trump-contra-anthropic\/","url":"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/27\/una-jueza-pone-en-pausa-la-ofensiva-de-trump-contra-anthropic\/","name":"Una jueza pone en pausa la ofensiva de Trump contra Anthropic - TecnoArtesanos Tech Blog","isPartOf":{"@id":"https:\/\/blog.tecnoartesanos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/27\/una-jueza-pone-en-pausa-la-ofensiva-de-trump-contra-anthropic\/#primaryimage"},"image":{"@id":"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/27\/una-jueza-pone-en-pausa-la-ofensiva-de-trump-contra-anthropic\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.tecnoartesanos.com\/wp-content\/uploads\/2026\/03\/una-jueza-pone-en-pausa-la-ofensiva-de-trump-contra-anthropic.jpg","datePublished":"2026-03-27T16:42:02+00:00","author":{"@id":"https:\/\/blog.tecnoartesanos.com\/#\/schema\/person\/ec88bc1410fd158963717c4216f04807"},"breadcrumb":{"@id":"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/27\/una-jueza-pone-en-pausa-la-ofensiva-de-trump-contra-anthropic\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/27\/una-jueza-pone-en-pausa-la-ofensiva-de-trump-contra-anthropic\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/27\/una-jueza-pone-en-pausa-la-ofensiva-de-trump-contra-anthropic\/#primaryimage","url":"https:\/\/blog.tecnoartesanos.com\/wp-content\/uploads\/2026\/03\/una-jueza-pone-en-pausa-la-ofensiva-de-trump-contra-anthropic.jpg","contentUrl":"https:\/\/blog.tecnoartesanos.com\/wp-content\/uploads\/2026\/03\/una-jueza-pone-en-pausa-la-ofensiva-de-trump-contra-anthropic.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/27\/una-jueza-pone-en-pausa-la-ofensiva-de-trump-contra-anthropic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.tecnoartesanos.com\/"},{"@type":"ListItem","position":2,"name":"Una jueza pone en pausa la ofensiva de Trump contra Anthropic"}]},{"@type":"WebSite","@id":"https:\/\/blog.tecnoartesanos.com\/#website","url":"https:\/\/blog.tecnoartesanos.com\/","name":"TecnoArtesanos Tech Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.tecnoartesanos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/blog.tecnoartesanos.com\/#\/schema\/person\/ec88bc1410fd158963717c4216f04807","name":"Sergio Morales","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blog.tecnoartesanos.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3d45178fc8fbbe32d39278bc504fa9093f947f406ff4f1ddcfa27505ab772184?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3d45178fc8fbbe32d39278bc504fa9093f947f406ff4f1ddcfa27505ab772184?s=96&d=mm&r=g","caption":"Sergio Morales"},"sameAs":["https:\/\/sergiomorales.space"],"url":"https:\/\/blog.tecnoartesanos.com\/index.php\/author\/sergiomorales\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/posts\/2440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/comments?post=2440"}],"version-history":[{"count":0,"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/posts\/2440\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/media\/2441"}],"wp:attachment":[{"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/media?parent=2440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/categories?post=2440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/tags?post=2440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}