{"id":2351,"date":"2026-03-03T13:37:53","date_gmt":"2026-03-03T13:37:53","guid":{"rendered":"http:\/\/698e7f0af81574a5d3807b82"},"modified":"2026-03-03T13:37:53","modified_gmt":"2026-03-03T13:37:53","slug":"esta-el-internet-al-borde-de-una-crisis-de-confianza","status":"publish","type":"post","link":"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/03\/esta-el-internet-al-borde-de-una-crisis-de-confianza\/","title":{"rendered":"\u00bfEst\u00e1 el Internet al borde de una crisis de confianza?"},"content":{"rendered":"<div class=\"media_block\"><img decoding=\"async\" src=\"https:\/\/media.es.wired.com\/photos\/69a4db4566bf22dfea07844b\/master\/pass\/Entrevista.jpg\" class=\"media_thumbnail\"><\/div>\n<div><img decoding=\"async\" src=\"https:\/\/media.es.wired.com\/photos\/69a4db4566bf22dfea07844b\/16:9\/w_1280,c_limit\/Entrevista.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p>En suma, estas herramientas permiten establecer l\u00edmites, supervisar contenidos y comprender mejor la actividad digital de ni\u00f1os y adolescentes, pero el primer paso, quiz\u00e1s el m\u00e1s importante, consiste en activarlas. \u201cEste es uno de los mayores retos que tengo: <strong>concientizar a los padres de la necesidad de decirnos exactamente la edad de sus hijos para que podamos poner todos estos candados<\/strong>&#8220;, indica la especialista de Google desde su oficina en S\u00e3o Paulo. Los sistemas de filtrado de contenido, las restricciones publicitarias y otras salvaguardas dependen de esa informaci\u00f3n. Sin ella, la experiencia digital de un menor puede parecerse a la de un adulto, con exposici\u00f3n a publicidad o materiales no adecuados.<\/p>\n<p>La situaci\u00f3n ilustrada por Couto refleja un problema de mayor consideraci\u00f3n: la brecha entre las herramientas disponibles y su uso real. Muchas familias desconocen funciones de seguridad b\u00e1sicas o no comprenden su importancia, lo que limita la confianza en cualquier estrategia de ciberseguridad. Tal es el caso de las <a href=\"https:\/\/es.wired.com\/articulos\/guia-wired-para-proteger-tu-identidad-en-linea\">herramientas de autenticaci\u00f3n<\/a>. Durante d\u00e9cadas, las contrase\u00f1as fueron la principal barrera (a menudo la \u00fanica) para proteger nuestros dispositivos o perfiles de ojos ajenos, pero hoy representan un punto de m\u00e1xima vulnerabilidad: se reutilizan, se anotan en papel o son tan simples que cualquiera podr\u00eda adivinarlas en un par de intentos.<\/p>\n<h2>Deja de escribir 1-2-3-4-5-6 y dale chance a las <em>passkeys<\/em><\/h2>\n<p><a href=\"https:\/\/es.wired.com\/articulos\/como-funcionan-las-passkeys-y-como-utilizarlas\">Las <em>passkeys<\/em><\/a> (llaves o claves de acceso) son un m\u00e9todo de inicio de sesi\u00f3n que reemplaza las viejas contrase\u00f1as por credenciales criptogr\u00e1ficas almacenadas en un dispositivo y desbloqueadas con tu huella, rostro o PIN. No obstante, su adopci\u00f3n enfrenta resistencias culturales y generacionales. Para muchas personas mayores, estas tecnolog\u00edas resultan dif\u00edciles de comprender o generan desconfianza. Parad\u00f3jicamente, suelen ser m\u00e1s seguras que las contrase\u00f1as tradicionales. Un tel\u00e9fono robado, por ejemplo, puede bloquearse autom\u00e1ticamente o a distancia, reduciendo el riesgo de acceso no autorizado. Pero estas funciones solo sirven si los usuarios saben que existen y si hay suficiente confianza en ellas.<\/p>\n<p>\u201cS\u00ed, este es un gran problema, porque aunque hoy hablamos cada vez m\u00e1s del uso de otras formas de iniciar sesi\u00f3n en nuestros productos y servicios, <strong>sabemos que existe una gran desconfianza hacia las nuevas tecnolog\u00edas<\/strong>\u201d, admite Couto a WIRED. \u201cHemos impulsado cada vez m\u00e1s programas de educaci\u00f3n y concientizaci\u00f3n sobre su funcionamiento y la necesidad de adoptarlas, ya que, en \u00faltima instancia, har\u00e1n que la experiencia en el entorno digital sea m\u00e1s segura\u201d.<\/p>\n<p>A\u00f1adi\u00f3: \u201cLo s\u00e9 porque no ocurre solo en M\u00e9xico; aqu\u00ed mismo, en Brasil, por ejemplo, mi mam\u00e1, que tiene 72 a\u00f1os, encuentra muy dif\u00edcil no solo entender c\u00f3mo se utilizan estas nuevas tecnolog\u00edas, sino tambi\u00e9n por qu\u00e9 son m\u00e1s seguras que una contrase\u00f1a. Sin embargo, cuando vemos a muchas personas con sus contrase\u00f1as escritas en hojas de papel dentro de la cartera, basta con que ocurra algo, como un robo, para que todo se pierda. En cambio, si configuras el reconocimiento facial, eso no suceder\u00e1. Podr\u00edan robarte el celular, pero no podr\u00e1n realizar el reconocimiento facial en ese momento y, por lo tanto, no tendr\u00e1n forma de acceder al dispositivo\u201d.<\/p>\n<h2>La seguridad digital del futuro es ya<\/h2>\n<p>En Am\u00e9rica Latina, la discusi\u00f3n sobre confianza digital se entrelaza con debates pol\u00edticos y culturales sobre el uso indebido de datos biom\u00e9tricos. Nuevos sistemas de identificaci\u00f3n gubernamental, como la <a href=\"https:\/\/es.wired.com\/articulos\/la-curp-biometrica-ya-es-oficial-como-tramitarla-y-que-datos-concentrara\">CURP biom\u00e9trica<\/a> en M\u00e9xico, despiertan temores sobre vigilancia de Estado, filtraciones o centralizaci\u00f3n de informaci\u00f3n sensible susceptible al hackeo.<\/p>\n<p>\u201cYo no puedo hablar sobre lo que el gobierno mexicano hace con los datos, pero puedo decirte que en relaci\u00f3n a Google, nosotros procedemos con todos los cuidados necesarios\u201d. Desde la perspectiva corporativa que representa Priscila Couto, la protecci\u00f3n de datos debe ser prioritaria desde el dise\u00f1o de cualquier producto o servicio. La privacidad no puede a\u00f1adirse despu\u00e9s; constituye el n\u00facleo de la relaci\u00f3n de confianza con los usuarios. <strong>\u201cEs el punto cero de cualquier cosa que hagamos, porque nosotros somos una empresa de tecnolog\u00eda y si algo pasa con los datos personales de nuestros usuarios, es el fin para nosotros\u201d<\/strong>, indica la experta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En suma, estas herramientas permiten establecer l\u00edmites, supervisar contenidos y comprender mejor la actividad digital de ni\u00f1os y adolescentes, pero el primer paso, quiz\u00e1s el m\u00e1s importante, consiste en activarlas. \u201cEste es uno de los mayores retos que tengo: concientizar a los padres de la necesidad de decirnos exactamente la edad de sus hijos para [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2352,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technology"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfEst\u00e1 el Internet al borde de una crisis de confianza? - TecnoArtesanos Tech Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/03\/esta-el-internet-al-borde-de-una-crisis-de-confianza\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfEst\u00e1 el Internet al borde de una crisis de confianza? - TecnoArtesanos Tech Blog\" \/>\n<meta property=\"og:description\" content=\"En suma, estas herramientas permiten establecer l\u00edmites, supervisar contenidos y comprender mejor la actividad digital de ni\u00f1os y adolescentes, pero el primer paso, quiz\u00e1s el m\u00e1s importante, consiste en activarlas. \u201cEste es uno de los mayores retos que tengo: concientizar a los padres de la necesidad de decirnos exactamente la edad de sus hijos para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/03\/esta-el-internet-al-borde-de-una-crisis-de-confianza\/\" \/>\n<meta property=\"og:site_name\" content=\"TecnoArtesanos Tech Blog\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-03T13:37:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.es.wired.com\/photos\/69a4db4566bf22dfea07844b\/master\/pass\/Entrevista.jpg\" \/>\n<meta name=\"author\" content=\"Sergio Morales\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sergio Morales\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/03\/esta-el-internet-al-borde-de-una-crisis-de-confianza\/\",\"url\":\"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/03\/esta-el-internet-al-borde-de-una-crisis-de-confianza\/\",\"name\":\"\u00bfEst\u00e1 el Internet al borde de una crisis de confianza? - TecnoArtesanos Tech Blog\",\"isPartOf\":{\"@id\":\"https:\/\/blog.tecnoartesanos.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/03\/esta-el-internet-al-borde-de-una-crisis-de-confianza\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/03\/esta-el-internet-al-borde-de-una-crisis-de-confianza\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.tecnoartesanos.com\/wp-content\/uploads\/2026\/03\/esta-el-internet-al-borde-de-una-crisis-de-confianza.jpg\",\"datePublished\":\"2026-03-03T13:37:53+00:00\",\"author\":{\"@id\":\"https:\/\/blog.tecnoartesanos.com\/#\/schema\/person\/ec88bc1410fd158963717c4216f04807\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/03\/esta-el-internet-al-borde-de-una-crisis-de-confianza\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/03\/esta-el-internet-al-borde-de-una-crisis-de-confianza\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/03\/esta-el-internet-al-borde-de-una-crisis-de-confianza\/#primaryimage\",\"url\":\"https:\/\/blog.tecnoartesanos.com\/wp-content\/uploads\/2026\/03\/esta-el-internet-al-borde-de-una-crisis-de-confianza.jpg\",\"contentUrl\":\"https:\/\/blog.tecnoartesanos.com\/wp-content\/uploads\/2026\/03\/esta-el-internet-al-borde-de-una-crisis-de-confianza.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/03\/esta-el-internet-al-borde-de-una-crisis-de-confianza\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.tecnoartesanos.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfEst\u00e1 el Internet al borde de una crisis de confianza?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.tecnoartesanos.com\/#website\",\"url\":\"https:\/\/blog.tecnoartesanos.com\/\",\"name\":\"TecnoArtesanos Tech Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.tecnoartesanos.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blog.tecnoartesanos.com\/#\/schema\/person\/ec88bc1410fd158963717c4216f04807\",\"name\":\"Sergio Morales\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/blog.tecnoartesanos.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3d45178fc8fbbe32d39278bc504fa9093f947f406ff4f1ddcfa27505ab772184?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3d45178fc8fbbe32d39278bc504fa9093f947f406ff4f1ddcfa27505ab772184?s=96&d=mm&r=g\",\"caption\":\"Sergio Morales\"},\"sameAs\":[\"https:\/\/sergiomorales.space\"],\"url\":\"https:\/\/blog.tecnoartesanos.com\/index.php\/author\/sergiomorales\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfEst\u00e1 el Internet al borde de una crisis de confianza? - TecnoArtesanos Tech Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/03\/esta-el-internet-al-borde-de-una-crisis-de-confianza\/","og_locale":"en_US","og_type":"article","og_title":"\u00bfEst\u00e1 el Internet al borde de una crisis de confianza? - TecnoArtesanos Tech Blog","og_description":"En suma, estas herramientas permiten establecer l\u00edmites, supervisar contenidos y comprender mejor la actividad digital de ni\u00f1os y adolescentes, pero el primer paso, quiz\u00e1s el m\u00e1s importante, consiste en activarlas. \u201cEste es uno de los mayores retos que tengo: concientizar a los padres de la necesidad de decirnos exactamente la edad de sus hijos para [&hellip;]","og_url":"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/03\/esta-el-internet-al-borde-de-una-crisis-de-confianza\/","og_site_name":"TecnoArtesanos Tech Blog","article_published_time":"2026-03-03T13:37:53+00:00","og_image":[{"url":"https:\/\/media.es.wired.com\/photos\/69a4db4566bf22dfea07844b\/master\/pass\/Entrevista.jpg","type":"","width":"","height":""}],"author":"Sergio Morales","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Sergio Morales","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/03\/esta-el-internet-al-borde-de-una-crisis-de-confianza\/","url":"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/03\/esta-el-internet-al-borde-de-una-crisis-de-confianza\/","name":"\u00bfEst\u00e1 el Internet al borde de una crisis de confianza? - TecnoArtesanos Tech Blog","isPartOf":{"@id":"https:\/\/blog.tecnoartesanos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/03\/esta-el-internet-al-borde-de-una-crisis-de-confianza\/#primaryimage"},"image":{"@id":"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/03\/esta-el-internet-al-borde-de-una-crisis-de-confianza\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.tecnoartesanos.com\/wp-content\/uploads\/2026\/03\/esta-el-internet-al-borde-de-una-crisis-de-confianza.jpg","datePublished":"2026-03-03T13:37:53+00:00","author":{"@id":"https:\/\/blog.tecnoartesanos.com\/#\/schema\/person\/ec88bc1410fd158963717c4216f04807"},"breadcrumb":{"@id":"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/03\/esta-el-internet-al-borde-de-una-crisis-de-confianza\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/03\/esta-el-internet-al-borde-de-una-crisis-de-confianza\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/03\/esta-el-internet-al-borde-de-una-crisis-de-confianza\/#primaryimage","url":"https:\/\/blog.tecnoartesanos.com\/wp-content\/uploads\/2026\/03\/esta-el-internet-al-borde-de-una-crisis-de-confianza.jpg","contentUrl":"https:\/\/blog.tecnoartesanos.com\/wp-content\/uploads\/2026\/03\/esta-el-internet-al-borde-de-una-crisis-de-confianza.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/blog.tecnoartesanos.com\/index.php\/2026\/03\/03\/esta-el-internet-al-borde-de-una-crisis-de-confianza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.tecnoartesanos.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfEst\u00e1 el Internet al borde de una crisis de confianza?"}]},{"@type":"WebSite","@id":"https:\/\/blog.tecnoartesanos.com\/#website","url":"https:\/\/blog.tecnoartesanos.com\/","name":"TecnoArtesanos Tech Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.tecnoartesanos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/blog.tecnoartesanos.com\/#\/schema\/person\/ec88bc1410fd158963717c4216f04807","name":"Sergio Morales","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blog.tecnoartesanos.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3d45178fc8fbbe32d39278bc504fa9093f947f406ff4f1ddcfa27505ab772184?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3d45178fc8fbbe32d39278bc504fa9093f947f406ff4f1ddcfa27505ab772184?s=96&d=mm&r=g","caption":"Sergio Morales"},"sameAs":["https:\/\/sergiomorales.space"],"url":"https:\/\/blog.tecnoartesanos.com\/index.php\/author\/sergiomorales\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/posts\/2351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/comments?post=2351"}],"version-history":[{"count":0,"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/posts\/2351\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/media\/2352"}],"wp:attachment":[{"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/media?parent=2351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/categories?post=2351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.tecnoartesanos.com\/index.php\/wp-json\/wp\/v2\/tags?post=2351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}